{"id":78,"date":"2011-12-27T11:40:44","date_gmt":"2011-12-27T11:40:44","guid":{"rendered":"http:\/\/www.aiasport.it\/?page_id=78"},"modified":"2026-06-27T15:23:19","modified_gmt":"2026-06-27T15:23:19","slug":"attivita-sportiva","status":"publish","type":"page","link":"https:\/\/www.aiasport.it\/index.php\/attivita-sportiva\/","title":{"rendered":"Attivit\u00e0 sportiva"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"945\" height=\"739\" src=\"https:\/\/www.aiasport.it\/wp-content\/uploads\/2026\/05\/706417244_122310935300202631_2354693256352124318_n.jpg\" alt=\"\" class=\"wp-image-7193\" style=\"aspect-ratio:1.5077881619937694;width:369px;height:auto\" srcset=\"https:\/\/www.aiasport.it\/wp-content\/uploads\/2026\/05\/706417244_122310935300202631_2354693256352124318_n.jpg 945w, https:\/\/www.aiasport.it\/wp-content\/uploads\/2026\/05\/706417244_122310935300202631_2354693256352124318_n-590x461.jpg 590w, https:\/\/www.aiasport.it\/wp-content\/uploads\/2026\/05\/706417244_122310935300202631_2354693256352124318_n-192x150.jpg 192w, https:\/\/www.aiasport.it\/wp-content\/uploads\/2026\/05\/706417244_122310935300202631_2354693256352124318_n-768x601.jpg 768w, https:\/\/www.aiasport.it\/wp-content\/uploads\/2026\/05\/706417244_122310935300202631_2354693256352124318_n-870x680.jpg 870w\" sizes=\"(max-width: 945px) 100vw, 945px\" \/><\/figure><\/div>\n\n\n<h3 class=\"wp-block-heading has-large-font-size\" style=\"font-style:normal;font-weight:400\">Attraverso lo sport una persona pu\u00f2 scoprire abilit\u00e0 che non credeva di possedere, o concretizzare competenze, facendo s\u00ec che diventino reali, attive, fruibili, e generalizzabili ad altri contesti.<\/h3>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\" style=\"font-style:normal;font-weight:400\">Il gruppo sportivo \u00e8 un gruppo di persone che desidera approfondire l\u2019attivit\u00e0 equestre dal punto di vista dell\u2019EQUITAZIONE.<\/h3>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\" style=\"font-style:normal;font-weight:400\">L\u2019 appartenenza al gruppo sportivo non implica necessariamente la partecipazione a gare, ma \u00e8 un modo di affrontare l\u2019attivit\u00e0 a cavallo come sport, in modo regolare e continuativo. Gli atleti del gruppo sportivo si possono confrontare dapprima a livello sociale, partecipando ai concorsi equestri organizzati dall\u2019ASD AIASPORT APS, per poi arrivare a competere a livello Regionale, Nazionale e, perch\u00e9 no, Internazionale.<\/h3>\n\n\n\n<div style=\"height:17px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-larger-font-size\" style=\"font-style:normal;font-weight:400\"><strong>L\u2019EQUITAZIONE \u00e8 SPORT PARALIMPICO a tutti gli effetti!<\/strong><\/h3>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\" style=\"font-style:normal;font-weight:400\"><img loading=\"lazy\" decoding=\"async\" width=\"399\" height=\"600\" class=\"alignleft  wp-image-596\" style=\"width: 400px;\" src=\"http:\/\/www.aiasport.it\/wp-content\/uploads\/2011\/12\/Fiamma-Canavesi06.jpg\" alt=\"\" srcset=\"https:\/\/www.aiasport.it\/wp-content\/uploads\/2011\/12\/Fiamma-Canavesi06.jpg 399w, https:\/\/www.aiasport.it\/wp-content\/uploads\/2011\/12\/Fiamma-Canavesi06-99x150.jpg 99w\" sizes=\"(max-width: 399px) 100vw, 399px\" \/><\/h3>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\" style=\"font-style:normal;font-weight:400\">Il livello di benessere personale \u00e8 strettamente legato alla possibilit\u00e0 di gestire autonomamente il proprio tempo libero, all\u2019interno del quale pu\u00f2 avere sicuramente una parte di grande importanza e rilievo lo sport, che d\u00e0 la possibilit\u00e0 alle persone disabili, come a tutti gli altri, di scoprire ed esprimere le proprie capacit\u00e0, incrementarle e migliorare la propria qualit\u00e0 di vita.<\/h3>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Attraverso lo sport una persona pu\u00f2 scoprire abilit\u00e0 che non credeva di possedere, o concretizzare competenze, facendo s\u00ec che diventino reali, attive, fruibili, e generalizzabili ad altri contesti. Il gruppo sportivo \u00e8 un gruppo di persone che desidera approfondire l\u2019attivit\u00e0 equestre dal punto di vista dell\u2019EQUITAZIONE. L\u2019 appartenenza al gruppo sportivo non implica necessariamente la &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.aiasport.it\/index.php\/attivita-sportiva\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":1,"featured_media":7204,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"template-onecolumn.php","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/www.aiasport.it\/index.php\/wp-json\/wp\/v2\/pages\/78"}],"collection":[{"href":"https:\/\/www.aiasport.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.aiasport.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.aiasport.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aiasport.it\/index.php\/wp-json\/wp\/v2\/comments?post=78"}],"version-history":[{"count":9,"href":"https:\/\/www.aiasport.it\/index.php\/wp-json\/wp\/v2\/pages\/78\/revisions"}],"predecessor-version":[{"id":7281,"href":"https:\/\/www.aiasport.it\/index.php\/wp-json\/wp\/v2\/pages\/78\/revisions\/7281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aiasport.it\/index.php\/wp-json\/wp\/v2\/media\/7204"}],"wp:attachment":[{"href":"https:\/\/www.aiasport.it\/index.php\/wp-json\/wp\/v2\/media?parent=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}